{"id":10718,"date":"2023-06-01T08:41:43","date_gmt":"2023-06-01T12:41:43","guid":{"rendered":"https:\/\/radioparquecde.com\/?p=10718"},"modified":"2023-06-01T08:41:44","modified_gmt":"2023-06-01T12:41:44","slug":"tras-un-pedido-de-auxilio-de-suhijastra-hombre-fue-aprehendido","status":"publish","type":"post","link":"https:\/\/radioparquecde.com\/index.php\/2023\/06\/01\/tras-un-pedido-de-auxilio-de-suhijastra-hombre-fue-aprehendido\/","title":{"rendered":"Tras un pedido de auxilio de suHijastra, hombre fue aprehendido"},"content":{"rendered":"\n<p>Un hombre fue aprehendido por agentes policiales por un supuesto caso de violencia familiar luego que su hijastra adolescente pidiera auxilio. El sujeto mantuvo una fuerte discusi\u00f3n con su pareja y antes que pase a mayores la menor decidi\u00f3 pedir socorro por el Sistema 911. El procedimiento se realiz\u00f3 el martes a las 22:45 horas sobre la calle Leonardo Britos c\/ Choferes del Chaco, en el barrio Obrero.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/radioparquecde.com\/wp-content\/uploads\/2023\/06\/350508649_213537634869843_7431544179949346598_n-1024x1024.jpg\" alt=\"\" class=\"wp-image-10720\" srcset=\"https:\/\/radioparquecde.com\/wp-content\/uploads\/2023\/06\/350508649_213537634869843_7431544179949346598_n-1024x1024.jpg 1024w, https:\/\/radioparquecde.com\/wp-content\/uploads\/2023\/06\/350508649_213537634869843_7431544179949346598_n-300x300.jpg 300w, https:\/\/radioparquecde.com\/wp-content\/uploads\/2023\/06\/350508649_213537634869843_7431544179949346598_n-150x150.jpg 150w, https:\/\/radioparquecde.com\/wp-content\/uploads\/2023\/06\/350508649_213537634869843_7431544179949346598_n-768x768.jpg 768w, https:\/\/radioparquecde.com\/wp-content\/uploads\/2023\/06\/350508649_213537634869843_7431544179949346598_n-1536x1536.jpg 1536w, https:\/\/radioparquecde.com\/wp-content\/uploads\/2023\/06\/350508649_213537634869843_7431544179949346598_n.jpg 1544w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>La Comisar\u00eda <a><\/a>3ra report\u00f3 un supuesto caso de violencia familiar por el cual fue aprehendido Claudio Mois\u00e9s Alonzo Acosta (39), que posteriormente fue denunciado por su pareja Lisa Cristina Mart\u00ednez Coronel (36). Los uniformados indicaron que luego de una alerta del Sistema 911 acudieron a la vivienda de la pareja para verificar y procedieron a la aprehensi\u00f3n del supuesto agresor.<\/p>\n\n\n\n<p>La mujer coment\u00f3 a los intervinientes que se desentendi\u00f3 con su pareja por cuestiones personales y que se produjo una acalorada discusi\u00f3n. En ese momento su hija adolescente se encontraba de visita en la casa y del susto decidi\u00f3 pedir ayuda, antes que la situaci\u00f3n pase a mayores. El hombre fue sometido a la prueba de alcotest y dio negativo. El caso qued\u00f3 con la fiscal Susan Vega, de la unidad de lucha contra la violencia dom\u00e9stica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un hombre fue aprehendido por agentes policiales por un supuesto caso de violencia familiar luego&#8230;<\/p>\n","protected":false},"author":3,"featured_media":10721,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,6],"tags":[],"class_list":["post-10718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alto-parana","category-noticias"],"featured_image_urls":{"full":["https:\/\/radioparquecde.com\/wp-content\/uploads\/2023\/06\/350508649_213537634869843_7431544179949346598_n-1.jpg",1544,1544,false],"thumbnail":["https:\/\/radioparquecde.com\/wp-content\/uploads\/2023\/06\/350508649_213537634869843_7431544179949346598_n-1-150x150.jpg",150,150,true],"medium":["https:\/\/radioparquecde.com\/wp-content\/uploads\/2023\/06\/350508649_213537634869843_7431544179949346598_n-1-300x300.jpg",300,300,true],"medium_large":["https:\/\/radioparquecde.com\/wp-content\/uploads\/2023\/06\/350508649_213537634869843_7431544179949346598_n-1-768x768.jpg",640,640,true],"large":["https:\/\/radioparquecde.com\/wp-content\/uploads\/2023\/06\/350508649_213537634869843_7431544179949346598_n-1-1024x1024.jpg",640,640,true],"1536x1536":["https:\/\/radioparquecde.com\/wp-content\/uploads\/2023\/06\/350508649_213537634869843_7431544179949346598_n-1-1536x1536.jpg",1536,1536,true],"2048x2048":["https:\/\/radioparquecde.com\/wp-content\/uploads\/2023\/06\/350508649_213537634869843_7431544179949346598_n-1.jpg",1544,1544,false],"newsphere-slider-full":["https:\/\/radioparquecde.com\/wp-content\/uploads\/2023\/06\/350508649_213537634869843_7431544179949346598_n-1-1280x720.jpg",1280,720,true],"newsphere-featured":["https:\/\/radioparquecde.com\/wp-content\/uploads\/2023\/06\/350508649_213537634869843_7431544179949346598_n-1-1024x1024.jpg",1024,1024,true],"newsphere-medium":["https:\/\/radioparquecde.com\/wp-content\/uploads\/2023\/06\/350508649_213537634869843_7431544179949346598_n-1-720x380.jpg",720,380,true]},"author_info":{"display_name":"Editor","author_link":"https:\/\/radioparquecde.com\/index.php\/author\/editor\/"},"category_info":"<a href=\"https:\/\/radioparquecde.com\/index.php\/category\/alto-parana\/\" rel=\"category tag\">ALTO PARAN\u00c1<\/a> <a href=\"https:\/\/radioparquecde.com\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","tag_info":"Noticias","comment_count":"0","_links":{"self":[{"href":"https:\/\/radioparquecde.com\/index.php\/wp-json\/wp\/v2\/posts\/10718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioparquecde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioparquecde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioparquecde.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/radioparquecde.com\/index.php\/wp-json\/wp\/v2\/comments?post=10718"}],"version-history":[{"count":1,"href":"https:\/\/radioparquecde.com\/index.php\/wp-json\/wp\/v2\/posts\/10718\/revisions"}],"predecessor-version":[{"id":10722,"href":"https:\/\/radioparquecde.com\/index.php\/wp-json\/wp\/v2\/posts\/10718\/revisions\/10722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioparquecde.com\/index.php\/wp-json\/wp\/v2\/media\/10721"}],"wp:attachment":[{"href":"https:\/\/radioparquecde.com\/index.php\/wp-json\/wp\/v2\/media?parent=10718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioparquecde.com\/index.php\/wp-json\/wp\/v2\/categories?post=10718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioparquecde.com\/index.php\/wp-json\/wp\/v2\/tags?post=10718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}